{"id":61703260,"date":"2026-05-12T22:09:14","date_gmt":"2026-05-12T22:09:14","guid":{"rendered":"https:\/\/api.ibilimenaje.com\/productos\/8832-anodized-round-deep-cake-pan\/"},"modified":"2026-05-12T22:09:14","modified_gmt":"2026-05-12T22:09:14","slug":"8832-anodized-round-deep-cake-pan","status":"publish","type":"productos","link":"https:\/\/api.ibilimenaje.com\/en\/productos\/8832-anodized-round-deep-cake-pan\/","title":{"rendered":"8832-anodized-round-deep-cake-pan"},"content":{"rendered":"<p>815030 Anodized Aluminum anodized mould  ##8411922089417## ###anodized-2###  ####27715288####  #@#-en_US#@#72903-en_US#@#5979-en_US#@# <\/p>\n","protected":false},"featured_media":61703290,"template":"","product_categories":[72903,5979],"class_list":["post-61703260","productos","type-productos","status-publish","has-post-thumbnail","hentry","product_categories-moldes-2772","product_categories-reposteria-2728","entry"],"acf":{"titulo_visible":"Anodized Round Deep Cake Pan","subtitle":" ","collection":[27715288],"is_new":false,"description":" ","tags_up":"","tags_down":"[\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_oven-230.svg\",\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_diswasher-no.svg\"]","images":"[\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_815015A-2.jpg\",\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_815015-2.jpg\",\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_815015B-2.jpg\"]","sizes":"[{\"Ref.\":\"815030\",\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_diamcm-1.svg\":\"30\",\"H (cm)\":\"7,6\",\"Lts\":\"5,5\",\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_ue.svg\":\"6\",\"Bar Code\":\"8411922089417\"}]","features":"","related_products":"","video":"","related_article":"","materials":"[\"Anodized Aluminum\"]","qr_redirect":"[\"https:\/\/www.ibilimenaje.com\/es\/p\/products\/d\/8832-molde-redondo-alto-anodizado\"]","downloads":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>8832-anodized-round-deep-cake-pan - Ibili Stage<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8832-anodized-round-deep-cake-pan - Ibili Stage\" \/>\n<meta property=\"og:description\" content=\"815030 Anodized Aluminum anodized mould ##8411922089417## ###anodized-2### ####27715288#### #@#-en_US#@#72903-en_US#@#5979-en_US#@#\" \/>\n<meta property=\"og:url\" content=\"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibili Stage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/\",\"url\":\"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/\",\"name\":\"8832-anodized-round-deep-cake-pan - Ibili Stage\",\"isPartOf\":{\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_815015A-2.jpg\",\"datePublished\":\"2026-05-12T22:09:14+00:00\",\"dateModified\":\"2026-05-12T22:09:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/#primaryimage\",\"url\":\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_815015A-2.jpg\",\"contentUrl\":\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_815015A-2.jpg\",\"width\":828,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/api.ibilimenaje.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"8832-anodized-round-deep-cake-pan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/#website\",\"url\":\"https:\/\/api.ibilimenaje.com\/es\/\",\"name\":\"Ibili Stage\",\"description\":\"Otro sitio realizado con WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/api.ibilimenaje.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"8832-anodized-round-deep-cake-pan - Ibili Stage","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"8832-anodized-round-deep-cake-pan - Ibili Stage","og_description":"815030 Anodized Aluminum anodized mould ##8411922089417## ###anodized-2### ####27715288#### #@#-en_US#@#72903-en_US#@#5979-en_US#@#","og_url":"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/","og_site_name":"Ibili Stage","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/","url":"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/","name":"8832-anodized-round-deep-cake-pan - Ibili Stage","isPartOf":{"@id":"https:\/\/api.ibilimenaje.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/#primaryimage"},"image":{"@id":"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/#primaryimage"},"thumbnailUrl":"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_815015A-2.jpg","datePublished":"2026-05-12T22:09:14+00:00","dateModified":"2026-05-12T22:09:14+00:00","breadcrumb":{"@id":"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/#primaryimage","url":"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_815015A-2.jpg","contentUrl":"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_815015A-2.jpg","width":828,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/api.ibilimenaje.com\/es\/productos\/8832-anodized-round-deep-cake-pan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/api.ibilimenaje.com\/es\/"},{"@type":"ListItem","position":2,"name":"8832-anodized-round-deep-cake-pan"}]},{"@type":"WebSite","@id":"https:\/\/api.ibilimenaje.com\/es\/#website","url":"https:\/\/api.ibilimenaje.com\/es\/","name":"Ibili Stage","description":"Otro sitio realizado con WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/api.ibilimenaje.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/api.ibilimenaje.com\/en\/wp-json\/wp\/v2\/productos\/61703260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/api.ibilimenaje.com\/en\/wp-json\/wp\/v2\/productos"}],"about":[{"href":"https:\/\/api.ibilimenaje.com\/en\/wp-json\/wp\/v2\/types\/productos"}],"acf:post":[{"embeddable":true,"href":"https:\/\/api.ibilimenaje.com\/en\/wp-json\/wp\/v2\/colecciones\/27715288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/api.ibilimenaje.com\/en\/wp-json\/wp\/v2\/media\/61703290"}],"wp:attachment":[{"href":"https:\/\/api.ibilimenaje.com\/en\/wp-json\/wp\/v2\/media?parent=61703260"}],"wp:term":[{"taxonomy":"product_categories","embeddable":true,"href":"https:\/\/api.ibilimenaje.com\/en\/wp-json\/wp\/v2\/product_categories?post=61703260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}