{"id":61740705,"date":"2026-05-12T22:18:28","date_gmt":"2026-05-12T22:18:28","guid":{"rendered":"https:\/\/api.ibilimenaje.com\/productos\/4165-dispensador-nespresso-vesubio\/"},"modified":"2026-05-12T22:18:28","modified_gmt":"2026-05-12T22:18:28","slug":"4165-dispensador-nespresso-vesubio","status":"publish","type":"productos","link":"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/","title":{"rendered":"4165-dispensador-nespresso-vesubio"},"content":{"rendered":"<p>780010 Acero Cromado Dispensador de c\u00e1pulas  ##8411922082302## #@#-es_ES#@#72926-es_ES#@#5953-es_ES#@# <\/p>\n","protected":false},"featured_media":61740712,"template":"","product_categories":[5953,72926],"class_list":["post-61740705","productos","type-productos","status-publish","has-post-thumbnail","hentry","product_categories-cafe-y-te-2726","product_categories-dispensadores-de-capsulas-2745","entry"],"acf":{"titulo_visible":"Dispensador Nespresso Vesubio","subtitle":"DISP.DE CAPSULAS NESPRESSO VESUBIO 36CA.","collection":null,"is_new":false,"description":"Dispensador de dise\u00f1o moderno para mantener ordenadas y a mano todas tus capsulas de caf\u00e9.","tags_up":"","tags_down":"","images":"[\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_780010.jpg\"]","sizes":"[{\"Ref.\":\"780010\",\"L (cm)\":\"13\",\"W (cm)\":\"9\",\"H (cm)\":\"22\",\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_ue.svg\":\"1\/12\",\"Bar Code\":\"8411922082302\"}]","features":"","related_products":"[{\"title\":\"Tarro para Cafu00e9 \/ Azu00facar + Cucharilla\",\"uri\":\"\/productos\/16174-tarro-para-cafe-azucar-cucharilla\",\"imgsrc\":\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_688608.jpg\"},{\"title\":\"Dispensador Nespresso Volcano\",\"uri\":\"\/productos\/4161-dispensador-nespresso-volcano\",\"imgsrc\":\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_720920.jpg\"},{\"title\":\"Dispensador Nespresso Fuji\",\"uri\":\"\/productos\/4162-dispensador-nespresso-fuji\",\"imgsrc\":\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_780020.jpg\"},{\"title\":\"Dispensador Nespresso Tambora\",\"uri\":\"\/productos\/4164-dispensador-nespresso-tambora\",\"imgsrc\":\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_780030.jpg\"}]","video":"","related_article":"","materials":"[\"Acero Cromado\"]","qr_redirect":"[\"https:\/\/www.ibilimenaje.com\/es\/p\/products\/d\/4165-dispensador-nespresso-vesubio\"]","downloads":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>4165-dispensador-nespresso-vesubio - Ibili Stage<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4165-dispensador-nespresso-vesubio - Ibili Stage\" \/>\n<meta property=\"og:description\" content=\"780010 Acero Cromado Dispensador de c\u00e1pulas ##8411922082302## #@#-es_ES#@#72926-es_ES#@#5953-es_ES#@#\" \/>\n<meta property=\"og:url\" content=\"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibili Stage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/\",\"url\":\"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/\",\"name\":\"4165-dispensador-nespresso-vesubio - Ibili Stage\",\"isPartOf\":{\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_780010.jpg\",\"datePublished\":\"2026-05-12T22:18:28+00:00\",\"dateModified\":\"2026-05-12T22:18:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/#primaryimage\",\"url\":\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_780010.jpg\",\"contentUrl\":\"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_780010.jpg\",\"width\":647,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/api.ibilimenaje.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4165-dispensador-nespresso-vesubio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/api.ibilimenaje.com\/es\/#website\",\"url\":\"https:\/\/api.ibilimenaje.com\/es\/\",\"name\":\"Ibili Stage\",\"description\":\"Otro sitio realizado con WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/api.ibilimenaje.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4165-dispensador-nespresso-vesubio - Ibili Stage","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"4165-dispensador-nespresso-vesubio - Ibili Stage","og_description":"780010 Acero Cromado Dispensador de c\u00e1pulas ##8411922082302## #@#-es_ES#@#72926-es_ES#@#5953-es_ES#@#","og_url":"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/","og_site_name":"Ibili Stage","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/","url":"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/","name":"4165-dispensador-nespresso-vesubio - Ibili Stage","isPartOf":{"@id":"https:\/\/api.ibilimenaje.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/#primaryimage"},"image":{"@id":"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/#primaryimage"},"thumbnailUrl":"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_780010.jpg","datePublished":"2026-05-12T22:18:28+00:00","dateModified":"2026-05-12T22:18:28+00:00","breadcrumb":{"@id":"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/#primaryimage","url":"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_780010.jpg","contentUrl":"https:\/\/api.ibilimenaje.com\/wp-content\/uploads\/2026\/05\/IMAGE__IMPORTED_6a03a2feee3f0_780010.jpg","width":647,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/api.ibilimenaje.com\/es\/productos\/4165-dispensador-nespresso-vesubio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/api.ibilimenaje.com\/es\/"},{"@type":"ListItem","position":2,"name":"4165-dispensador-nespresso-vesubio"}]},{"@type":"WebSite","@id":"https:\/\/api.ibilimenaje.com\/es\/#website","url":"https:\/\/api.ibilimenaje.com\/es\/","name":"Ibili Stage","description":"Otro sitio realizado con WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/api.ibilimenaje.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/api.ibilimenaje.com\/es\/wp-json\/wp\/v2\/productos\/61740705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/api.ibilimenaje.com\/es\/wp-json\/wp\/v2\/productos"}],"about":[{"href":"https:\/\/api.ibilimenaje.com\/es\/wp-json\/wp\/v2\/types\/productos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/api.ibilimenaje.com\/es\/wp-json\/wp\/v2\/media\/61740712"}],"wp:attachment":[{"href":"https:\/\/api.ibilimenaje.com\/es\/wp-json\/wp\/v2\/media?parent=61740705"}],"wp:term":[{"taxonomy":"product_categories","embeddable":true,"href":"https:\/\/api.ibilimenaje.com\/es\/wp-json\/wp\/v2\/product_categories?post=61740705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}